{"id":7079,"date":"2026-01-12T21:43:33","date_gmt":"2026-01-12T20:43:33","guid":{"rendered":"https:\/\/www.nwhp.at\/?p=7079"},"modified":"2026-01-12T21:44:57","modified_gmt":"2026-01-12T20:44:57","slug":"verluste-reklamieren-gewinne-behalten%ef%bf%bc","status":"publish","type":"post","link":"https:\/\/www.nwhp.at\/en\/verluste-reklamieren-gewinne-behalten%ef%bf%bc\/","title":{"rendered":"Verluste reklamieren, Gewinne behalten?\ufffc"},"content":{"rendered":"\n<p class=\"has-drop-cap\"><strong>Warum es bei einheitlichen Tatsachenkomplexen jedenfalls beim Verbot des Rosinenpickens bleiben sollte.<\/strong><\/p>\n\n\n\n<p>Darf ein Anleger Verluste einklagen, w\u00e4hrend er Gewinne aus derselben Veranlagung beh\u00e4lt? Genau mit dieser Frage wird sich der Oberste Gerichtshof in einem aktuellen Verfahren befassen. K\u00fcrzlich wurde bekannt gegeben, dass die Rechtssache dem achten Senat zugewiesen wurde \u2013 eine Entscheidung (8 Ob 1\/26v) ist daher in absehbarer Zeit zu erwarten.<\/p>\n\n\n\n<p>Der Kl\u00e4ger hatte \u00fcber seinen Verm\u00f6gensberater in mehrere M.-Fonds, konkret in f\u00fcnf verschiedene, n\u00e4mlich die Fonds 3, 7, 9, 11 und 13 investiert und insgesamt einen Schaden in H\u00f6he von EUR 17.264,75 jedoch nur aus der Investition in die Fonds 3, 11 und 13 klageweise gegen\u00fcber seinem Verm\u00f6gensberater (unserem Mandanten) geltend gemacht. Zus\u00e4tzlich begehrte der Kl\u00e4ger die Feststellung, dass der Beklagte aufgrund rechtswidrigen und schuldhaften Verhaltens, insbesondere fehlerhafter Beratung gegen\u00fcber dem Kl\u00e4ger in Zusammenhang mit dessen Beteiligungen an den Fondsgesellschaften 3, 11 und 13 f\u00fcr alle zuk\u00fcnftigen Sch\u00e4den haftet, welche der Kl\u00e4ger zus\u00e4tzlich zum bereits eingetretenen Schaden daraus erleiden wird.<\/p>\n\n\n\n<p>Kurzum forderte der Kl\u00e4ger die Verluste aus den Fonds 3, 11 und 13 und verlangte, dass der Verm\u00f6gensberater auch f\u00fcr m\u00f6gliche weitere Sch\u00e4den haftet, da er ihn aus Sicht des Kl\u00e4gers falsch beraten hatte. Seine Gewinne aus den \u00fcbrigen Fonds wollte er in diesem Verfahren nicht thematisieren, da es sich seiner Meinung nach um einzelne Vertr\u00e4ge und sohin gesonderte Veranlagungen und keine einheitliche Gesamtveranlagung handelte.<\/p>\n\n\n\n<p>Demgegen\u00fcber steht der Standpunkt unseres Mandanten, der sich auch im erst- und zweitinstanzlichen Urteil widerspiegelt: Es handelt sich um eine einheitliche Gesamtveranlagung. Der Kl\u00e4ger investierte <strong>am selben Tag, am selben Ort und auf Grundlage einer einheitlichen Beratung insgesamt EUR 36.000 in f\u00fcnf M.-Fonds<\/strong>. Dabei wollte er zun\u00e4chst nur den aktuellen zeichnen. Die Aufteilung auf mehrere Fonds erfolgte dann aber zur Risikostreuung ausschlie\u00dflich auf Empfehlung des Beklagten.<\/p>\n\n\n\n<p>Wirtschaftlich betrachtet ergibt sich ein deutliches Bild: Den Verlusten aus einzelnen Fonds bzw. der Gesamtinvestition des Kl\u00e4gers in H\u00f6he von EUR 36.000,00 stehen Aussch\u00fcttungen in H\u00f6he von insgesamt EUR 132.290,00 gegen\u00fcber \u2013 das entspricht einer <strong>Gesamtverzinsung von nicht weniger als rund<\/strong> <strong>285 %.<\/strong> Von einem Schaden kann aus Sicht des Beklagten daher keine Rede sein. Ein selektives \u201eHerauspicken\u201c nur der verlustbringenden Fonds w\u00fcrde zu unbilligen Ergebnissen f\u00fchren, da Gewinne und Verluste untrennbar aus demselben Tatsachenkomplex stammen.<\/p>\n\n\n\n<p>Dass der OGH sich damit \u00fcberhaupt noch besch\u00e4ftigen muss, ist \u00fcberraschend, da es eindeutige, in den Senaten auch einheitliche Judikatur dazu gibt. Nach der Entscheidung 7 Ob 106\/19t, in der der OGH ausf\u00fchrlich die Parameter f\u00fcr die Vorteilsanrechnung darlegt, ist ein Vorteilsausgleich dann anzunehmen, wenn<\/p>\n\n\n\n<ol type=\"1\"><li>das sch\u00e4digende Ereignis nach dem gew\u00f6hnlichen Lauf der Dinge auch einen Vorteil im Verm\u00f6gen des Gesch\u00e4digten verursachte (RS0022824 [T3]),<\/li><li>Schaden und Vorteil im selben Tatsachenkomplex wurzeln (RS0022824 [T2]),<\/li><li>Zeitliche und sachliche Kongruenz vorliegt (vgl. RS0114259) und<\/li><li>die Erwerbsvorg\u00e4nge auf einem Beratungsgespr\u00e4ch mit innerem, kausalem Zusammenhang im Rahmen des Gesamtkonzepts erfolgt sind.<\/li><\/ol>\n\n\n\n<p>Alle diese Voraussetzungen wurden sowohl durch die Feststellungen des Erstgerichtes als auch durch jene des Berufungsgerichtes best\u00e4tigt, weshalb im Ergebnis ein Schaden im Verm\u00f6gen des Kl\u00e4gers unserem Rechtsstandpunkt nach auch nicht entstanden ist.<\/p>\n\n\n\n<p>Auch die geforderte Gesamttransaktion im Sinne der Entscheidung 8 Ob 6\/10f liegt vor. Dort hei\u00dft es ebenso, dass \u201eeine zergliedernde Betrachtung des gesamten Vertragswerks zu Ergebnissen f\u00fchren [w\u00fcrde], die bei wirtschaftlicher Betrachtung unhaltbar erscheinen\u201c. Eine Zergliederung, die nur f\u00fcr den Standpunkt der Kl\u00e4gerin vorteilhaften Teile aus einem komplexen Vertragsb\u00fcndel herausgreift, ist nicht vertretbar (\u201eRosinentheorie\u201c).<\/p>\n\n\n\n<p>Zuletzt verweist der OGH in der Entscheidung 1 Ob 159\/19t unter 3.3. darauf, dass Voraussetzung f\u00fcr einen Vorteilsausgleich ganz allgemein die Kausalit\u00e4t des haftbar machenden Ereignisses ist, sowohl f\u00fcr den Nachteil als auch f\u00fcr den Vorteil (vgl. RS0118820). Es sind nur Vorteile des Gesch\u00e4digten anrechenbar, die mit dem Schadenersatzanspruch in einem besonderen Zusammenhang stehen. Vor- und Nachteile m\u00fcssen zwar nicht im selben Ereignis, aber im selben Tatsachenkomplex \u2013 hier vorliegend, weil er EUR 36.000,00 in einen M.-Fonds investieren wollte und dann aus Streuungsgr\u00fcnden auf mehrere M.-Fonds aufgeteilt hatte \u2013 wurzeln (vgl. RS0022824).<\/p>\n\n\n\n<p>Gerade bei Verm\u00f6gensberatungen ist es \u00fcblich, dass nicht \u2013 wie bei einer jahrelangen Betreuung durch einen Bankberater oder einer langfristig angelegten Verm\u00f6gensverwaltung \u2013 laufend einzelne Transaktionen vorgenommen werden. Stattdessen wird auf Grundlage einer einmaligen Gesamtentscheidung das vorhandene Verm\u00f6gen auf mehrere Produkte verteilt, um Risiken zu streuen. Die einheitliche Willensentscheidung sowie die zeitliche und sachliche Kongruenz sind in solchen F\u00e4llen regelm\u00e4\u00dfig gegeben.<\/p>\n\n\n\n<p>Ob der achte Senat diese Frage trotz der bereits vorliegenden Entscheidungen \u2013 insbesondere dazu, wann ein Vorteilsausgleich vorzunehmen ist und wann nicht \u2013 in diesem Einzelfall erneut aufgreifen wird und gegebenenfalls wie, bleibt abzuwarten.<\/p>\n\n\n\n<p><em>Autoren:<\/em><\/p>\n\n\n\n<p><em>Mag. Dominique Perl ist Rechtsanw\u00e4ltin in Wien und arbeitet in st\u00e4ndiger Kooperation mit Neumayer &amp; Walter Rechtsanw\u00e4lte KG. Mag. Ulrich Walter ist Partner der Neumayer &amp; Walter Rechtsanw\u00e4lte KG. Beide sind st\u00e4ndig im Kapitalmarkt- und Anlegerrecht t\u00e4tig.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Warum es bei einheitlichen Tatsachenkomplexen jedenfalls beim Verbot des Rosinenpickens bleiben sollte. Darf ein Anleger Verluste einklagen, w\u00e4hrend er Gewinne aus derselben Veranlagung beh\u00e4lt? Genau mit dieser Frage wird sich der Oberste Gerichtshof in einem aktuellen Verfahren befassen. K\u00fcrzlich wurde bekannt gegeben, dass die Rechtssache dem achten Senat zugewiesen wurde \u2013 eine Entscheidung (8 Ob [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[90,100],"tags":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/posts\/7079"}],"collection":[{"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/comments?post=7079"}],"version-history":[{"count":1,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/posts\/7079\/revisions"}],"predecessor-version":[{"id":7080,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/posts\/7079\/revisions\/7080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/media\/7081"}],"wp:attachment":[{"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/media?parent=7079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/categories?post=7079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/tags?post=7079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}