{"id":43,"date":"2009-12-19T10:01:01","date_gmt":"2009-12-19T08:01:01","guid":{"rendered":"http:\/\/creativeunit.at\/nwhp\/amis-ogh-erklaert-msk-fuer-unzulaessig-freie-anwaltswahl-zwingend\/"},"modified":"2009-12-19T10:01:01","modified_gmt":"2009-12-19T08:01:01","slug":"amis-ogh-erklaert-msk-fuer-unzulaessig-freie-anwaltswahl-zwingend","status":"publish","type":"post","link":"https:\/\/www.nwhp.at\/en\/amis-ogh-erklaert-msk-fuer-unzulaessig-freie-anwaltswahl-zwingend\/","title":{"rendered":"AMIS OGH erkl\u00e4rt MSk f\u00fcr unzul\u00e4ssig &#8211; freie Anwaltswahl zwingend"},"content":{"rendered":"<p>OGH erkl\u00e4rt Massenschadenklausel in Rechtschutzversicherung f\u00fcr unzul\u00e4ssig \u2013 OGH h\u00e4lt fest, dass<br \/>\u00a0<br \/>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 freie Anwaltswahl zwingend<br \/>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 wodurch eine individuelle Vertretung von Versicherungsnehmern gew\u00e4hrleistet wird<br \/>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OGH erkl\u00e4rt Massenschadenklausel in Rechtschutzversicherung f\u00fcr unzul\u00e4ssig \u2013 OGH h\u00e4lt fest, dass\u00a0\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 freie Anwaltswahl zwingend\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 wodurch eine individuelle Vertretung von Versicherungsnehmern gew\u00e4hrleistet wird\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/posts\/43"}],"collection":[{"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":0,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/posts\/43\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/media?parent=43"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/categories?post=43"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nwhp.at\/en\/wp-json\/wp\/v2\/tags?post=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}